{"id":7528,"date":"2016-02-29T13:43:51","date_gmt":"2016-02-29T12:43:51","guid":{"rendered":"http:\/\/www.schiedsrichter.at\/?p=7528"},"modified":"2018-02-01T15:59:56","modified_gmt":"2018-02-01T14:59:56","slug":"20160229_novelle_2015_zum_bundesvergabegesetz","status":"publish","type":"post","link":"https:\/\/www.schiedsrichter.at\/en\/20160229_novelle_2015_zum_bundesvergabegesetz\/","title":{"rendered":"Novelle 2015 zum Bundesvergabegesetz"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a570f1f73d721_01807239 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a570f1f73d721_01807239 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n<\/style><div id=\"cmsmasters_row_6a570f1f73d721_01807239\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<h1>Novelle 2015 zum Bundesvergabegesetz tritt am 01.03.2016 in Kraft<\/h1>\n<h3><span style=\"color: #d43555;\">Die Novelle 2015 zum Bundesvergabegesetz wurde am 29.02.2016 im BGBl I Nr 7\/2016 verlautbart.<br \/>\n<\/span><\/h3>\n<div class=\"cmsmasters_dropcap type1\">D<\/div>ie Novelle 2015 zum Bundesvergabegesetz 2006, mit welcher Teile der neuen Vergaberichtlinien 2014\/24\/EU und 2014\/25\/EU in \u00f6sterreichisches Recht umgesetzt werden, hat eine lange Entstehungsgeschichte. Die Regierungsvorlage zur Novelle wurde bereits am 10.04.2015 vorgelegt. Nach der Verabschiedung der Novelle im Nationalrat wurde der Beschluss im Bundesrat durch die Abgeordneten des Bundeslandes Tirol im November 2015 verhindert, obwohl gerade das Land Tirol in der Vergangenheit als Bef\u00fcrworter des Bestbieterpinzips aufgetreten ist. Nach geringf\u00fcgigen \u00c4nderungen der Novelle wurde sie schlie\u00dflich am 10.12.2015 im Nationalrat und am 17.12.2015 im Bundesrat abgesegnet. Anschlie\u00dfend wurde der Gesetzesbeschluss den L\u00e4ndern zur Zustimmung \u00fcbermittelt werden. Nachdem binnen 8 Wochen nach Zustellung kein Land die Zustimmung verweigerte, wurde die Novelle heute, am 29.02.2016, im Bundesgesetzblatt I Nr 7\/2016 publiziert, sodass sie gleich morgen am 01.03.2016 in Kraft treten kann.<\/p>\n<p>Hauptinhalt der Novelle sind<\/p>\n<ul>\n<li>die St\u00e4rkung des <strong>Bestbieterprinzips<\/strong>, zB verpflichtend bei der Vergabe geistiger Dienstleistungen oder bei Bauauftr\u00e4gen mit einem Auftragswert \u00fcber EUR 1 Mio,<\/li>\n<li><strong>Subunternehmerketten<\/strong>, also die St\u00e4rkung der Information und der Kontrollm\u00f6glichkeit des Auftraggebers im Hinblick auf die bei Ausf\u00fchrung des Auftrages tats\u00e4chlich eingesetzten Unternehmer,<\/li>\n<li>die <strong>Bek\u00e4mpfung des Lohn- und Sozialdumpings<\/strong> durch verpflichtende Einholung einer Auskunft aus der Verwaltungsstrafevidenz des Kompetenzzentrums LSDB durch den Auftraggeber und<\/li>\n<li>Klarstellungen bei der Losvergabe und der vertieften Angebotspr\u00fcfung.<\/li>\n<\/ul>\n<p>F\u00fcr \u00f6ffentliche Auftraggeber ist diese Vorgangsweise des Gesetzgebers beim In-Kraft-Treten der Novelle nicht gerade komfortabel. Nachdem monatelang Unsichterheit \u00fcber das Schicksal der geplanten Novelle geherrscht hat, ist die verlautbarte Novelle innerhalb eines Tages f\u00fcr neue Vergabeverfahren umzusetzen. Mit den jeweiligen Neuerungen sind allerdings zum Teil aufw\u00e4ndige \u00c4nderungen der Ausschreibungsunterlagen verbunden, sodass diese Vorgangsweise des Gesetzgebers nicht gerade zur Schaffung von Rechtssicherheit bei anstehenden Vergabeverfahren beitr\u00e4gt. Viele \u00f6ffentliche Auftraggeber haben allerdings die Neuerungen schon vor ihrer Verlautbarung antizipiert und mit Vorarbeiten zur Umsetzung begonnen. Dennoch wird die Novelle, vor allem das verpflichtende Bestbieterprinzip, so manche Probleme in der t\u00e4glichen Vergabepraxis aufwerfen.<\/p>\n<p><em>von Dr. G\u00fcnther Gast<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Die Novelle 2015 zum Bundesvergabegesetz wurde am 29.02.2016 im BGBl I Nr 7\/2016 verlautbart<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/posts\/7528"}],"collection":[{"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/comments?post=7528"}],"version-history":[{"count":5,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/posts\/7528\/revisions"}],"predecessor-version":[{"id":7533,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/posts\/7528\/revisions\/7533"}],"wp:attachment":[{"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/media?parent=7528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/categories?post=7528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schiedsrichter.at\/en\/wp-json\/wp\/v2\/tags?post=7528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}